{"id":7043,"date":"2023-11-15T19:22:59","date_gmt":"2023-11-15T19:22:59","guid":{"rendered":"https:\/\/anasac.com\/?p=7043"},"modified":"2025-08-04T12:56:57","modified_gmt":"2025-08-04T16:56:57","slug":"demostracion-de-variedades-de-hortalizas-anasac-en-la-araucania-cultivando-el-futuro-de-forma-sostenible","status":"publish","type":"post","link":"https:\/\/anasac.com\/en\/demostracion-de-variedades-de-hortalizas-anasac-en-la-araucania-cultivando-el-futuro-de-forma-sostenible\/","title":{"rendered":"DEMOSTRACI\u00d3N DE VARIEDADES DE HORTALIZAS ANASAC EN LA ARAUCAN\u00cdA: CULTIVANDO EL FUTURO DE FORMA SOSTENIBLE"},"content":{"rendered":"<p>En el mes de octubre, nos sumergimos en la apasionante experiencia de realizar nuestro primer demostrativo de hortalizas cruc\u00edferas en las localidades de Vilc\u00fan y Freire, en la hermosa regi\u00f3n de La Araucan\u00eda. Esta enriquecedora actividad cont\u00f3 con la participaci\u00f3n destacada de un grupo de j\u00f3venes horticultores, miembros activos de la cooperativa agr\u00edcola de hortalizas \u00abEl Natre\u00bb y recientes integrantes de nuestro exitoso modelo de incubadora socio-productiva, dise\u00f1ado y perfeccionado en la misma regi\u00f3n.<\/p>\n<p>En esta ocasi\u00f3n \u00fanica, decidimos impulsar un demostrativo en una hect\u00e1rea de tierra, donde se exhibir\u00e1 el rendimiento y la calidad gen\u00e9tica de las variedades de semillas de Anasac. Entre ellas, destacan los plantines de Coliflor, representados por las fascinantes variedades Kimbo y Balto, as\u00ed como los plantines de Repollo, encabezados por las variadas opciones de Sake y Fausto. Adem\u00e1s, evaluaremos la eficacia de una amplia gama de productos, tanto convencionales como biol\u00f3gicos, pertenecientes a nuestra l\u00ednea de protecci\u00f3n de cultivos, que han sido rigurosamente probados desde la fase inicial hasta su completa madurez.<\/p>\n<p>En nuestro compromiso con la agricultura sostenible, hemos forjado un modo de cultivar que no solo cuida la tierra, sino tambi\u00e9n a sus habitantes. Tomamos decisiones fundamentadas en informaci\u00f3n precisa, trabajando incansablemente para fomentar el desarrollo social, econ\u00f3mico y ambiental en los territorios en los que intervenimos, siempre con el m\u00e1ximo respeto por sus tradiciones e identidad.<\/p>","protected":false},"excerpt":{"rendered":"<p>En el mes de octubre, nos sumergimos en la apasionante experiencia de realizar nuestro primer demostrativo de hortalizas cruc\u00edferas en las localidades de Vilc\u00fan y Freire, en la hermosa regi\u00f3n de La Araucan\u00eda. Esta enriquecedora actividad cont\u00f3 con la participaci\u00f3n destacada de un grupo de j\u00f3venes horticultores, miembros activos de la cooperativa agr\u00edcola de hortalizas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-7043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilidad-anasac-chile"],"_links":{"self":[{"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/posts\/7043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/comments?post=7043"}],"version-history":[{"count":1,"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/posts\/7043\/revisions"}],"predecessor-version":[{"id":10722,"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/posts\/7043\/revisions\/10722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/media\/7046"}],"wp:attachment":[{"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/media?parent=7043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/categories?post=7043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anasac.com\/en\/wp-json\/wp\/v2\/tags?post=7043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}